  {"id":7492,"date":"2022-04-08T02:35:15","date_gmt":"2022-04-08T00:35:15","guid":{"rendered":"https:\/\/alba.progresium.cz\/?page_id=7492"},"modified":"2023-06-07T23:21:23","modified_gmt":"2023-06-07T21:21:23","slug":"medizin-und-pflege","status":"publish","type":"page","link":"https:\/\/alba.progresium.cz\/de\/loesungen\/medizin-und-pflege\/","title":{"rendered":"Medizin und Pflege"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"7492\" class=\"elementor elementor-7492\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2a33ea13 header_section elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2a33ea13\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-593f84fa\" data-id=\"593f84fa\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-4c059a92 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4c059a92\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-4200ed39\" data-id=\"4200ed39\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-62b5345f elementor-widget elementor-widget-heading\" data-id=\"62b5345f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Medizin und Pflege<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5e9082a0 elementor-widget elementor-widget-heading\" data-id=\"5e9082a0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Wir bieten Sitzkomfort f\u00fcr \u00c4rzte, Labortechniker, medizinisches Fachpersonal und Patienten<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-6d0bb023\" data-id=\"6d0bb023\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-48287bd8 single_c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"48287bd8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f78e681\" data-id=\"f78e681\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-22f4eef4 elementor-widget elementor-widget-ucaddon_alba_perex\" data-id=\"22f4eef4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"ucaddon_alba_perex.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<!-- start ALBA perex -->\n\n<div class=\"article_perex\">In unserem Angebot finden Sie auch spezielle St\u00fchle f\u00fcr Bereiche, in denen Komfort und Langlebigkeit mit h\u00f6chster Hygiene Hand in Hand gehen m\u00fcssen. Tausende Menschen, sowohl Patienten als auch Fachkr\u00e4fte, begegnen ALBA-Sitzm\u00f6beln in einer Vielzahl von spezialisierten Einrichtungen.<\/div>\n<!-- end ALBA perex -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2307035 elementor-widget elementor-widget-text-editor\" data-id=\"2307035\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Wir stellen St\u00fchle und Sessel f\u00fcr \u00c4rzte, Laboranten und medizinisches Personal sowie Sitzm\u00f6bel f\u00fcr Wartebereiche, Kundenzimmer und andere Bereiche her und lassen dabei unsere Erfahrungen aus der Praxis in unsere Modelle einflie\u00dfen. Eine um 360 Grad separat drehbare Lehne f\u00fcr mehr Arbeitskomfort, Stufenlose Sitzh\u00f6henverstellung mit Ringausl\u00f6sung sowie zertifizierte Oberfl\u00e4chenmaterialien f\u00fcr eine einfache hygienische Reinigung &#8211; das sind nur einige der spezifischen Details dieser Produktreihe.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-eeed0cf elementor-widget elementor-widget-button\" data-id=\"eeed0cf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/alba.progresium.cz\/de\/kontakt\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Angebot f\u00fcr Medizin- und Pflegewesen anfordern<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7e8bb114 dual_c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7e8bb114\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-49421469\" data-id=\"49421469\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6b991dcd elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"6b991dcd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-392f335c dual_c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"392f335c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-7ab9583b\" data-id=\"7ab9583b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-385c95f9 elementor-widget elementor-widget-text-editor\" data-id=\"385c95f9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3>H\u00f6chster Sitzomfort f\u00fcr maximale Konzentration<\/h3><p>Eine gesunde K\u00f6rperhaltung beim Sitzen wird nicht nur im Gesundheitswesen durch einen ergonomischen Qualit\u00e4tsstuhl gew\u00e4hrleistet, der mehr als nur H\u00f6henverstellbar ist. Der Sitz und die anatomisch geformte R\u00fcckenlehne, gegebenenfalls mit zus\u00e4tzlicher Kopfst\u00fctze und verstellbaren Armlehnen, m\u00fcssen es auch erlauben, den Stuhl an die Bed\u00fcrfnisse verschiedener Benutzer anzupassen.<\/p><p>Nur so l\u00e4sst sich lang anhaltender Sitzkomfort in der Arztpraxis oder in anderen medizinischen Einrichtungen erreichen, ohne dabei den R\u00fccken zu belasten oder die Konzentrationsf\u00e4higkeit zu beeintr\u00e4chtigen. Das medizinische Personal profitiert auch sehr von der Mobilit\u00e4t des Stuhls, die durch die Rollen erm\u00f6glicht wird, deren Material je nach Bodenart variiert.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-6c1672ed\" data-id=\"6c1672ed\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4fc357d0 elementor-widget elementor-widget-image\" data-id=\"4fc357d0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1920\" height=\"1280\" src=\"https:\/\/alba.progresium.cz\/wp-content\/uploads\/2022\/02\/Medical_Nemocnice_Havlickuv_Brod.jpg\" class=\"attachment-full size-full wp-image-7530\" alt=\"\" srcset=\"https:\/\/alba.progresium.cz\/wp-content\/uploads\/2022\/02\/Medical_Nemocnice_Havlickuv_Brod.jpg 1920w, https:\/\/alba.progresium.cz\/wp-content\/uploads\/2022\/02\/Medical_Nemocnice_Havlickuv_Brod-300x200.jpg 300w, https:\/\/alba.progresium.cz\/wp-content\/uploads\/2022\/02\/Medical_Nemocnice_Havlickuv_Brod-1024x683.jpg 1024w, https:\/\/alba.progresium.cz\/wp-content\/uploads\/2022\/02\/Medical_Nemocnice_Havlickuv_Brod-768x512.jpg 768w, https:\/\/alba.progresium.cz\/wp-content\/uploads\/2022\/02\/Medical_Nemocnice_Havlickuv_Brod-1536x1024.jpg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6cbb218d dual_c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6cbb218d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-13e5908f\" data-id=\"13e5908f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-150276a1 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"150276a1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3231f9a single_c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3231f9a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-41274768\" data-id=\"41274768\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-62efb310 elementor-widget elementor-widget-image\" data-id=\"62efb310\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"830\" height=\"380\" src=\"https:\/\/alba.progresium.cz\/wp-content\/uploads\/2022\/02\/7-1024x469.jpg\" class=\"attachment-large size-large wp-image-7531\" alt=\"\" srcset=\"https:\/\/alba.progresium.cz\/wp-content\/uploads\/2022\/02\/7-1024x469.jpg 1024w, https:\/\/alba.progresium.cz\/wp-content\/uploads\/2022\/02\/7-300x138.jpg 300w, https:\/\/alba.progresium.cz\/wp-content\/uploads\/2022\/02\/7-768x352.jpg 768w, https:\/\/alba.progresium.cz\/wp-content\/uploads\/2022\/02\/7-1536x704.jpg 1536w, https:\/\/alba.progresium.cz\/wp-content\/uploads\/2022\/02\/7-2048x939.jpg 2048w\" sizes=\"(max-width: 830px) 100vw, 830px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-623dbf26 elementor-widget elementor-widget-text-editor\" data-id=\"623dbf26\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3>Hygiene steht an erster Stelle<\/h3><p>In den Wartebereichen von medizinischen Einrichtungen, die t\u00e4glich von einer gro\u00dfen Anzahl von Patienten aufgesucht werden, ist die Langlebigkeit und die einfache hygienische Reinigung der Sitzm\u00f6bel von besonderer Bedeutung. Bei ALBA wird dies durch die Verwendung hochwertiger, stabiler Metallgestelle und den Einsatz von Sitzen und R\u00fcckenlehnen aus strapazierf\u00e4higen und leicht zu reinigenden Materialien wie Kunststoff, Holz oder Metall erreicht.<\/p><p>Mehr Sitzkomfort erreichen Sie durch Polsterung der St\u00fchle oder B\u00e4nke mit einem unserer erstklassigen, widerstandsf\u00e4higen Stoffe. Sitzm\u00f6bel f\u00fcr medizinische Einrichtungen k\u00f6nnen auch mit bakteriostatischem Stoff oder speziellem medizinischen Kunstleder bezogen werden, das in mehreren attraktiven Farben erh\u00e4ltlich ist.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e1d7e5d dual_c inv_b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e1d7e5d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-383f489a\" data-id=\"383f489a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-721cc460 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"721cc460\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-5f403804\" data-id=\"5f403804\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5751b2b3 elementor-widget elementor-widget-image\" data-id=\"5751b2b3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"650\" height=\"1024\" src=\"https:\/\/alba.progresium.cz\/wp-content\/uploads\/2022\/01\/Medik_ze-strany-650x1024.jpg\" class=\"attachment-large size-large wp-image-7524\" alt=\"\" srcset=\"https:\/\/alba.progresium.cz\/wp-content\/uploads\/2022\/01\/Medik_ze-strany-650x1024.jpg 650w, https:\/\/alba.progresium.cz\/wp-content\/uploads\/2022\/01\/Medik_ze-strany-191x300.jpg 191w, https:\/\/alba.progresium.cz\/wp-content\/uploads\/2022\/01\/Medik_ze-strany.jpg 762w\" sizes=\"(max-width: 650px) 100vw, 650px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-59fabbb2\" data-id=\"59fabbb2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6439b65d elementor-widget elementor-widget-text-editor\" data-id=\"6439b65d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3>MEDIC ist die deale L\u00f6sung f\u00fcr medizinische Fachkr\u00e4fte<\/h3><p>MEDIC wurde speziell f\u00fcr das Gesundheitswesen entwickelt und geht auf die besonderen Bed\u00fcrfnisse von \u00c4rzten und medizinischem Fachpersonal ein. Die verwendeten Materialien entsprechen den Vorschriften f\u00fcr medizinische Einrichtungen, dar\u00fcber hinaus bietet MEDIC eine Auswahl an zus\u00e4tzlichen Sitzh\u00f6hen und eine um 360 Grad separat drehbare Lehne, die als R\u00fccken- oder Armlehne genutzt werden kann, was den Positionswechsel w\u00e4hrend des Tages erm\u00f6glicht und einseitige Belastung verhindert. Die Ringausl\u00f6sung erm\u00f6glicht eine stufenfreie Einstellung der Sitzh\u00f6he und ist bequem von allen Seiten zug\u00e4nglich.<\/p><p>Die einfache hygienische Wartung ist durch medizinisches Kunstleder oder einen der bakteriostatischen Stoffe aus unserem Sortiment gew\u00e4hrleistet. In Kombination mit einer sorgf\u00e4ltig verarbeiteten Konstruktion und einem optimalen ergonomischen Design garantieren die medizinischen St\u00fchle von ALBA absoluten Arbeitskomfort.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9391725 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9391725\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2dd545c\" data-id=\"2dd545c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a6bed23 elementor-widget elementor-widget-shortcode\" data-id=\"a6bed23\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\">\t\t<div data-elementor-type=\"section\" data-elementor-id=\"26261\" class=\"elementor elementor-26261 elementor-26257\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-65e24f94 dual_c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"65e24f94\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-49484f62\" data-id=\"49484f62\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-254dac6 elementor-widget elementor-widget-text-editor\" data-id=\"254dac6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3>Haben Sie Interesse an Produkten von ALBA und m\u00f6chten sich mit uns in Verbindung setzen?<\/h3>\n<h2>\nKontaktieren Sie uns!<\/h2>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6b14c4a2 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"6b14c4a2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"tel:+420%20224%20284%20026\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-phone\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">+420 224 284 026<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"mailto:info@alba.progresium.cz\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-envelope\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">info@alba.progresium.cz<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/alba.progresium.cz\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-globe-africa\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">www.alba.progresium.cz<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-7abc9a72\" data-id=\"7abc9a72\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-79d24808 elementor-widget elementor-widget-shortcode\" data-id=\"79d24808\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><script>\nvar gform;gform||(document.addEventListener(\"gform_main_scripts_loaded\",function(){gform.scriptsLoaded=!0}),document.addEventListener(\"gform\/theme\/scripts_loaded\",function(){gform.themeScriptsLoaded=!0}),window.addEventListener(\"DOMContentLoaded\",function(){gform.domLoaded=!0}),gform={domLoaded:!1,scriptsLoaded:!1,themeScriptsLoaded:!1,isFormEditor:()=>\"function\"==typeof InitializeEditor,callIfLoaded:function(o){return!(!gform.domLoaded||!gform.scriptsLoaded||!gform.themeScriptsLoaded&&!gform.isFormEditor()||(gform.isFormEditor()&&console.warn(\"The use of gform.initializeOnLoaded() is deprecated in the form editor context and will be removed in Gravity Forms 3.1.\"),o(),0))},initializeOnLoaded:function(o){gform.callIfLoaded(o)||(document.addEventListener(\"gform_main_scripts_loaded\",()=>{gform.scriptsLoaded=!0,gform.callIfLoaded(o)}),document.addEventListener(\"gform\/theme\/scripts_loaded\",()=>{gform.themeScriptsLoaded=!0,gform.callIfLoaded(o)}),window.addEventListener(\"DOMContentLoaded\",()=>{gform.domLoaded=!0,gform.callIfLoaded(o)}))},hooks:{action:{},filter:{}},addAction:function(o,r,e,t){gform.addHook(\"action\",o,r,e,t)},addFilter:function(o,r,e,t){gform.addHook(\"filter\",o,r,e,t)},doAction:function(o){gform.doHook(\"action\",o,arguments)},applyFilters:function(o){return gform.doHook(\"filter\",o,arguments)},removeAction:function(o,r){gform.removeHook(\"action\",o,r)},removeFilter:function(o,r,e){gform.removeHook(\"filter\",o,r,e)},addHook:function(o,r,e,t,n){null==gform.hooks[o][r]&&(gform.hooks[o][r]=[]);var d=gform.hooks[o][r];null==n&&(n=r+\"_\"+d.length),gform.hooks[o][r].push({tag:n,callable:e,priority:t=null==t?10:t})},doHook:function(r,o,e){var t;if(e=Array.prototype.slice.call(e,1),null!=gform.hooks[r][o]&&((o=gform.hooks[r][o]).sort(function(o,r){return o.priority-r.priority}),o.forEach(function(o){\"function\"!=typeof(t=o.callable)&&(t=window[t]),\"action\"==r?t.apply(null,e):e[0]=t.apply(null,e)})),\"filter\"==r)return e[0]},removeHook:function(o,r,t,n){var e;null!=gform.hooks[o][r]&&(e=(e=gform.hooks[o][r]).filter(function(o,r,e){return!!(null!=n&&n!=o.tag||null!=t&&t!=o.priority)}),gform.hooks[o][r]=e)}});\n<\/script>\n\n                <div class='gf_browser_gecko gform_wrapper gform-theme gform-theme--foundation gform-theme--framework gform-theme--orbital' data-form-theme='orbital' data-form-index='0' id='gform_wrapper_1' ><style>#gform_wrapper_1[data-form-index=\"0\"].gform-theme,[data-parent-form=\"1_0\"]{--gf-color-primary: #204ce5;--gf-color-primary-rgb: 32, 76, 229;--gf-color-primary-contrast: #fff;--gf-color-primary-contrast-rgb: 255, 255, 255;--gf-color-primary-darker: #001AB3;--gf-color-primary-lighter: #527EFF;--gf-color-secondary: #fff;--gf-color-secondary-rgb: 255, 255, 255;--gf-color-secondary-contrast: #112337;--gf-color-secondary-contrast-rgb: 17, 35, 55;--gf-color-secondary-darker: #F5F5F5;--gf-color-secondary-lighter: #FFFFFF;--gf-color-out-ctrl-light: rgba(17, 35, 55, 0.1);--gf-color-out-ctrl-light-rgb: 17, 35, 55;--gf-color-out-ctrl-light-darker: rgba(104, 110, 119, 0.35);--gf-color-out-ctrl-light-lighter: #F5F5F5;--gf-color-out-ctrl-dark: #585e6a;--gf-color-out-ctrl-dark-rgb: 88, 94, 106;--gf-color-out-ctrl-dark-darker: #112337;--gf-color-out-ctrl-dark-lighter: rgba(17, 35, 55, 0.65);--gf-color-in-ctrl: #fff;--gf-color-in-ctrl-rgb: 255, 255, 255;--gf-color-in-ctrl-contrast: #112337;--gf-color-in-ctrl-contrast-rgb: 17, 35, 55;--gf-color-in-ctrl-darker: #F5F5F5;--gf-color-in-ctrl-lighter: #FFFFFF;--gf-color-in-ctrl-primary: #204ce5;--gf-color-in-ctrl-primary-rgb: 32, 76, 229;--gf-color-in-ctrl-primary-contrast: #fff;--gf-color-in-ctrl-primary-contrast-rgb: 255, 255, 255;--gf-color-in-ctrl-primary-darker: #001AB3;--gf-color-in-ctrl-primary-lighter: #527EFF;--gf-color-in-ctrl-light: rgba(17, 35, 55, 0.1);--gf-color-in-ctrl-light-rgb: 17, 35, 55;--gf-color-in-ctrl-light-darker: rgba(104, 110, 119, 0.35);--gf-color-in-ctrl-light-lighter: #F5F5F5;--gf-color-in-ctrl-dark: #585e6a;--gf-color-in-ctrl-dark-rgb: 88, 94, 106;--gf-color-in-ctrl-dark-darker: #112337;--gf-color-in-ctrl-dark-lighter: rgba(17, 35, 55, 0.65);--gf-radius: 3px;--gf-font-size-secondary: 14px;--gf-font-size-tertiary: 13px;--gf-icon-ctrl-number: url(\"data:image\/svg+xml,%3Csvg width='8' height='14' viewBox='0 0 8 14' fill='none' xmlns='http:\/\/www.w3.org\/2000\/svg'%3E%3Cpath fill-rule='evenodd' clip-rule='evenodd' d='M4 0C4.26522 5.96046e-08 4.51957 0.105357 4.70711 0.292893L7.70711 3.29289C8.09763 3.68342 8.09763 4.31658 7.70711 4.70711C7.31658 5.09763 6.68342 5.09763 6.29289 4.70711L4 2.41421L1.70711 4.70711C1.31658 5.09763 0.683417 5.09763 0.292893 4.70711C-0.0976311 4.31658 -0.097631 3.68342 0.292893 3.29289L3.29289 0.292893C3.48043 0.105357 3.73478 0 4 0ZM0.292893 9.29289C0.683417 8.90237 1.31658 8.90237 1.70711 9.29289L4 11.5858L6.29289 9.29289C6.68342 8.90237 7.31658 8.90237 7.70711 9.29289C8.09763 9.68342 8.09763 10.3166 7.70711 10.7071L4.70711 13.7071C4.31658 14.0976 3.68342 14.0976 3.29289 13.7071L0.292893 10.7071C-0.0976311 10.3166 -0.0976311 9.68342 0.292893 9.29289Z' fill='rgba(17, 35, 55, 0.65)'\/%3E%3C\/svg%3E\");--gf-icon-ctrl-select: url(\"data:image\/svg+xml,%3Csvg width='10' height='6' viewBox='0 0 10 6' fill='none' xmlns='http:\/\/www.w3.org\/2000\/svg'%3E%3Cpath fill-rule='evenodd' clip-rule='evenodd' d='M0.292893 0.292893C0.683417 -0.097631 1.31658 -0.097631 1.70711 0.292893L5 3.58579L8.29289 0.292893C8.68342 -0.0976311 9.31658 -0.0976311 9.70711 0.292893C10.0976 0.683417 10.0976 1.31658 9.70711 1.70711L5.70711 5.70711C5.31658 6.09763 4.68342 6.09763 4.29289 5.70711L0.292893 1.70711C-0.0976311 1.31658 -0.0976311 0.683418 0.292893 0.292893Z' fill='rgba(17, 35, 55, 0.65)'\/%3E%3C\/svg%3E\");--gf-icon-ctrl-search: url(\"data:image\/svg+xml,%3Csvg width='640' height='640' xmlns='http:\/\/www.w3.org\/2000\/svg'%3E%3Cpath d='M256 128c-70.692 0-128 57.308-128 128 0 70.691 57.308 128 128 128 70.691 0 128-57.309 128-128 0-70.692-57.309-128-128-128zM64 256c0-106.039 85.961-192 192-192s192 85.961 192 192c0 41.466-13.146 79.863-35.498 111.248l154.125 154.125c12.496 12.496 12.496 32.758 0 45.254s-32.758 12.496-45.254 0L367.248 412.502C335.862 434.854 297.467 448 256 448c-106.039 0-192-85.962-192-192z' fill='rgba(17, 35, 55, 0.65)'\/%3E%3C\/svg%3E\");--gf-label-space-y-secondary: var(--gf-label-space-y-md-secondary);--gf-ctrl-border-color: #686e77;--gf-ctrl-size: var(--gf-ctrl-size-md);--gf-ctrl-label-color-primary: #112337;--gf-ctrl-label-color-secondary: #112337;--gf-ctrl-choice-size: var(--gf-ctrl-choice-size-md);--gf-ctrl-checkbox-check-size: var(--gf-ctrl-checkbox-check-size-md);--gf-ctrl-radio-check-size: var(--gf-ctrl-radio-check-size-md);--gf-ctrl-btn-font-size: var(--gf-ctrl-btn-font-size-md);--gf-ctrl-btn-padding-x: var(--gf-ctrl-btn-padding-x-md);--gf-ctrl-btn-size: var(--gf-ctrl-btn-size-md);--gf-ctrl-btn-border-color-secondary: #686e77;--gf-ctrl-file-btn-bg-color-hover: #EBEBEB;--gf-field-img-choice-size: var(--gf-field-img-choice-size-md);--gf-field-img-choice-card-space: var(--gf-field-img-choice-card-space-md);--gf-field-img-choice-check-ind-size: var(--gf-field-img-choice-check-ind-size-md);--gf-field-img-choice-check-ind-icon-size: var(--gf-field-img-choice-check-ind-icon-size-md);--gf-field-pg-steps-number-color: rgba(17, 35, 55, 0.8);}<\/style><div id='gf_1' class='gform_anchor' tabindex='-1'><\/div><form method='post' enctype='multipart\/form-data' target='gform_ajax_frame_1' id='gform_1'  action='\/de\/wp-json\/wp\/v2\/pages\/7492#gf_1' data-formid='1' novalidate>\n                        <div class='gform-body gform_body'><div id='gform_fields_1' class='gform_fields top_label form_sublabel_below description_below validation_below'><div id=\"field_1_7\" class=\"gfield gfield--type-honeypot gform_validation_container field_sublabel_below gfield--has-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_1_7'>Phone<\/label><div class='ginput_container'><input name='input_7' id='input_1_7' type='text' value='' autocomplete='new-password'\/><\/div><div class='gfield_description' id='gfield_description_1_7'>Dieses Feld dient zur Validierung und sollte nicht ver\u00e4ndert werden.<\/div><\/div><div id=\"field_1_1\" class=\"gfield gfield--type-text gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_1_1'>Ihr Name<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_text\">(erforderlich)<\/span><\/span><\/label><div class='ginput_container ginput_container_text'><input name='input_1' id='input_1_1' type='text' value='' class=''     aria-required=\"true\" aria-invalid=\"false\"  autocomplete=\"name\" \/><\/div><\/div><div id=\"field_1_2\" class=\"gfield gfield--type-text gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_1_2'>Gesellschaft<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_text\">(erforderlich)<\/span><\/span><\/label><div class='ginput_container ginput_container_text'><input name='input_2' id='input_1_2' type='text' value='' class=''     aria-required=\"true\" aria-invalid=\"false\"  autocomplete=\"organization\" \/><\/div><\/div><div id=\"field_1_3\" class=\"gfield gfield--type-email gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_1_3'>Ihre E-Mail<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_text\">(erforderlich)<\/span><\/span><\/label><div class='ginput_container ginput_container_email'>\n                            <input name='input_3' id='input_1_3' type='email' value='' class=''    aria-required=\"true\" aria-invalid=\"false\"  autocomplete=\"email\"\/>\n                        <\/div><\/div><div id=\"field_1_4\" class=\"gfield gfield--type-phone gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_1_4'>Ihre Telefonnummer<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_text\">(erforderlich)<\/span><\/span><\/label><div class='ginput_container ginput_container_phone'><input name='input_4' id='input_1_4' type='tel' value='' class=''   aria-required=\"true\" aria-invalid=\"false\"  autocomplete=\"tel\" \/><\/div><\/div><div id=\"field_1_5\" class=\"gfield gfield--type-textarea gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_1_5'>Ihre Nachricht<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_text\">(erforderlich)<\/span><\/span><\/label><div class='ginput_container ginput_container_textarea'><textarea name='input_5' id='input_1_5' class='textarea '     aria-required=\"true\" aria-invalid=\"false\"   rows='10' cols='50'><\/textarea><\/div><\/div><div id=\"field_1_6\" class=\"gfield gfield--type-turnstile field_sublabel_below gfield--no-description field_description_below hidden_label field_validation_below gfield_visibility_visible\"  ><div class='ginput_container ginput_container_turnstile'><div class=\"cf-turnstile\" id=\"cf-turnstile_1\" data-js-turnstile data-response-field-name=\"cf-turnstile-response_1\" data-theme=\"light\" data-size=\"\" data-sitekey=\"0x4AAAAAADzyapKxLnTiIcbQ\"><\/div><\/div><\/div><\/div><\/div>\n        <div class='gform-footer gform_footer top_label'> <input type='submit' id='gform_submit_button_1' class='gform_button button' onclick='gform.submission.handleButtonClick(this);' data-submission-type='submit' value='Senden'  \/> <input type='hidden' name='gform_ajax' value='form_id=1&amp;title=&amp;description=&amp;tabindex=0&amp;theme=orbital&amp;styles=[]&amp;hash=fade0894870fbbd8be4b9485991fb882' \/>\n            <input type='hidden' class='gform_hidden' name='gform_submission_method' data-js='gform_submission_method_1' value='iframe' \/>\n            <input type='hidden' class='gform_hidden' name='gform_theme' data-js='gform_theme_1' id='gform_theme_1' value='orbital' \/>\n            <input type='hidden' class='gform_hidden' name='gform_style_settings' data-js='gform_style_settings_1' id='gform_style_settings_1' value='[]' \/>\n            <input type='hidden' class='gform_hidden' name='is_submit_1' value='1' \/>\n            <input type='hidden' class='gform_hidden' name='gform_submit' value='1' \/>\n            \n            <input type='hidden' class='gform_hidden' name='gform_currency' data-currency='USD' value='RMungyFPYpg\/yKnJdyXdaJiHGw8GPXYQboz4bCnne11M9MnNKRdLvsvomm28iIAHOtxO6BzP5EvmEGP1aSSjFf9rteXQvdRv1wdBH3TzQgnEetk=' \/>\n            <input type='hidden' class='gform_hidden' name='gform_unique_id' value='' \/>\n            <input type='hidden' class='gform_hidden' name='state_1' value='WyJbXSIsImQ2NzAzMjEzYThkYWU4OThmZjI5NmY1NDA5MzRmOGUwIl0=' \/>\n            <input type='hidden' autocomplete='off' class='gform_hidden' name='gform_target_page_number_1' id='gform_target_page_number_1' value='0' \/>\n            <input type='hidden' autocomplete='off' class='gform_hidden' name='gform_source_page_number_1' id='gform_source_page_number_1' value='1' \/>\n            <input type='hidden' name='gform_field_values' value='' \/>\n            \n        <\/div>\n                        <\/form>\n                        <\/div>\n\t\t                <iframe style='display:none;width:0px;height:0px;' src='about:blank' name='gform_ajax_frame_1' id='gform_ajax_frame_1' title='Dieser iframe enth\u00e4lt die erforderliche Logik um Gravity Forms Formulare mit AJAX zu handhaben.'><\/iframe>\n\t\t                <script>\ngform.initializeOnLoaded( function() {gformInitSpinner( 1, 'https:\/\/alba.progresium.cz\/wp-content\/plugins\/gravityforms\/images\/spinner.svg', false );jQuery('#gform_ajax_frame_1').on('load',function(){var contents = jQuery(this).contents().find('*').html();var is_postback = contents.indexOf('GF_AJAX_POSTBACK') >= 0;if(!is_postback){return;}var form_content = jQuery(this).contents().find('#gform_wrapper_1');var is_confirmation = jQuery(this).contents().find('#gform_confirmation_wrapper_1').length > 0;var is_redirect = contents.indexOf('gformRedirect(){') >= 0;var is_form = form_content.length > 0 && ! is_redirect && ! is_confirmation;var mt = parseInt(jQuery('html').css('margin-top'), 10) + parseInt(jQuery('body').css('margin-top'), 10) + 100;if(is_form){jQuery('#gform_wrapper_1').html(form_content.html());if(form_content.hasClass('gform_validation_error')){jQuery('#gform_wrapper_1').addClass('gform_validation_error');} else {jQuery('#gform_wrapper_1').removeClass('gform_validation_error');}setTimeout( function() { \/* delay the scroll by 50 milliseconds to fix a bug in chrome *\/ jQuery(document).scrollTop(jQuery('#gform_wrapper_1').offset().top - mt); }, 50 );if(window['gformInitDatepicker']) {gformInitDatepicker();}if(window['gformInitPriceFields']) {gformInitPriceFields();}var current_page = jQuery('#gform_source_page_number_1').val();gformInitSpinner( 1, 'https:\/\/alba.progresium.cz\/wp-content\/plugins\/gravityforms\/images\/spinner.svg', false );jQuery(document).trigger('gform_page_loaded', [1, current_page]);window['gf_submitting_1'] = false;}else if(!is_redirect){var confirmation_content = jQuery(this).contents().find('.GF_AJAX_POSTBACK').html();if(!confirmation_content){confirmation_content = contents;}jQuery('#gform_wrapper_1').replaceWith(confirmation_content);jQuery(document).scrollTop(jQuery('#gf_1').offset().top - mt);jQuery(document).trigger('gform_confirmation_loaded', [1]);window['gf_submitting_1'] = false;wp.a11y.speak(jQuery('#gform_confirmation_message_1').text());}else{jQuery('#gform_1').append(contents);if(window['gformRedirect']) {gformRedirect();}}jQuery(document).trigger(\"gform_pre_post_render\", [{ formId: \"1\", currentPage: \"current_page\", abort: function() { this.preventDefault(); } }]);        if (event && event.defaultPrevented) {                return;        }        const gformWrapperDiv = document.getElementById( \"gform_wrapper_1\" );        if ( gformWrapperDiv ) {            const visibilitySpan = document.createElement( \"span\" );            visibilitySpan.id = \"gform_visibility_test_1\";            gformWrapperDiv.insertAdjacentElement( \"afterend\", visibilitySpan );        }        const visibilityTestDiv = document.getElementById( \"gform_visibility_test_1\" );        let postRenderFired = false;        function triggerPostRender() {            if ( postRenderFired ) {                return;            }            postRenderFired = true;            gform.core.triggerPostRenderEvents( 1, current_page );            if ( visibilityTestDiv ) {                visibilityTestDiv.parentNode.removeChild( visibilityTestDiv );            }        }        function debounce( func, wait, immediate ) {            var timeout;            return function() {                var context = this, args = arguments;                var later = function() {                    timeout = null;                    if ( !immediate ) func.apply( context, args );                };                var callNow = immediate && !timeout;                clearTimeout( timeout );                timeout = setTimeout( later, wait );                if ( callNow ) func.apply( context, args );            };        }        const debouncedTriggerPostRender = debounce( function() {            triggerPostRender();        }, 200 );        if ( visibilityTestDiv && visibilityTestDiv.offsetParent === null ) {            const observer = new MutationObserver( ( mutations ) => {                mutations.forEach( ( mutation ) => {                    if ( mutation.type === 'attributes' && visibilityTestDiv.offsetParent !== null ) {                        debouncedTriggerPostRender();                        observer.disconnect();                    }                });            });            observer.observe( document.body, {                attributes: true,                childList: false,                subtree: true,                attributeFilter: [ 'style', 'class' ],            });        } else {            triggerPostRender();        }    } );} );\n<\/script>\n<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1068095b single_c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1068095b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5391046\" data-id=\"5391046\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-42686d88 elementor-widget elementor-widget-spacer\" data-id=\"42686d88\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Wir bieten Sitzkomfort f\u00fcr \u00c4rzte, Labortechniker, medizinisches Fachpersonal und Patienten In unserem Angebot finden Sie auch spezielle St\u00fchle f\u00fcr Bereiche, in denen Komfort und Langlebigkeit mit h\u00f6chster Hygiene Hand in Hand gehen m\u00fcssen. Tausende Menschen, sowohl Patienten als auch Fachkr\u00e4fte, begegnen ALBA-Sitzm\u00f6beln in einer Vielzahl von spezialisierten Einrichtungen. Wir stellen St\u00fchle und Sessel f\u00fcr \u00c4rzte, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":2292,"parent":7480,"menu_order":9,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"class_list":["post-7492","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.0.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"St\u00fchle und Sessel f\u00fcr \u00c4rzte, Labor und medizinisches Personal sowie M\u00f6bel f\u00fcr Warte- und Empfangsbereiche. 360\u00b0-Drehung und leicht zu reinigende Oberfl\u00e4chen.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/alba.progresium.cz\/de\/loesungen\/medizin-und-pflege\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.0.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"de_DE\" \/>\n\t\t<meta property=\"og:site_name\" content=\"ALBA Seating - European Chair Manufacturer\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"St\u00fchle f\u00fcr das Gesundheitswesen &amp; Praxen | ALBA Seating\" \/>\n\t\t<meta property=\"og:description\" content=\"St\u00fchle und Sessel f\u00fcr \u00c4rzte, Labor und medizinisches Personal sowie M\u00f6bel f\u00fcr Warte- und Empfangsbereiche. 360\u00b0-Drehung und leicht zu reinigende Oberfl\u00e4chen.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/alba.progresium.cz\/de\/loesungen\/medizin-und-pflege\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2022-04-08T00:35:15+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2023-06-07T21:21:23+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"St\u00fchle f\u00fcr das Gesundheitswesen &amp; Praxen | ALBA Seating\" \/>\n\t\t<meta name=\"twitter:description\" content=\"St\u00fchle und Sessel f\u00fcr \u00c4rzte, Labor und medizinisches Personal sowie M\u00f6bel f\u00fcr Warte- und Empfangsbereiche. 360\u00b0-Drehung und leicht zu reinigende Oberfl\u00e4chen.\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/alba.progresium.cz\\\/de\\\/loesungen\\\/medizin-und-pflege\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/alba.progresium.cz\\\/de\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/alba.progresium.cz\\\/de\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/alba.progresium.cz\\\/de\\\/loesungen\\\/#listItem\",\"name\":\"L\\u00f6sungen\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/alba.progresium.cz\\\/de\\\/loesungen\\\/#listItem\",\"position\":2,\"name\":\"L\\u00f6sungen\",\"item\":\"https:\\\/\\\/alba.progresium.cz\\\/de\\\/loesungen\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/alba.progresium.cz\\\/de\\\/loesungen\\\/medizin-und-pflege\\\/#listItem\",\"name\":\"Medizin und Pflege\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/alba.progresium.cz\\\/de\\\/#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/alba.progresium.cz\\\/de\\\/loesungen\\\/medizin-und-pflege\\\/#listItem\",\"position\":3,\"name\":\"Medizin und Pflege\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/alba.progresium.cz\\\/de\\\/loesungen\\\/#listItem\",\"name\":\"L\\u00f6sungen\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/alba.progresium.cz\\\/de\\\/#organization\",\"name\":\"ALBA Seating\",\"description\":\"European Chair Manufacturer\",\"url\":\"https:\\\/\\\/alba.progresium.cz\\\/de\\\/\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/alba.progresium.cz\\\/de\\\/loesungen\\\/medizin-und-pflege\\\/#webpage\",\"url\":\"https:\\\/\\\/alba.progresium.cz\\\/de\\\/loesungen\\\/medizin-und-pflege\\\/\",\"name\":\"St\\u00fchle f\\u00fcr das Gesundheitswesen & Praxen | ALBA Seating\",\"description\":\"St\\u00fchle und Sessel f\\u00fcr \\u00c4rzte, Labor und medizinisches Personal sowie M\\u00f6bel f\\u00fcr Warte- und Empfangsbereiche. 360\\u00b0-Drehung und leicht zu reinigende Oberfl\\u00e4chen.\",\"inLanguage\":\"de-DE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/alba.progresium.cz\\\/de\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/alba.progresium.cz\\\/de\\\/loesungen\\\/medizin-und-pflege\\\/#breadcrumblist\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/alba.progresium.cz\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/nemocnice1.jpg\",\"@id\":\"https:\\\/\\\/alba.progresium.cz\\\/de\\\/loesungen\\\/medizin-und-pflege\\\/#mainImage\",\"width\":1920,\"height\":694},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/alba.progresium.cz\\\/de\\\/loesungen\\\/medizin-und-pflege\\\/#mainImage\"},\"datePublished\":\"2022-04-08T02:35:15+02:00\",\"dateModified\":\"2023-06-07T23:21:23+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/alba.progresium.cz\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/alba.progresium.cz\\\/de\\\/\",\"name\":\"ALBA Seating\",\"description\":\"European Chair Manufacturer\",\"inLanguage\":\"de-DE\",\"publisher\":{\"@id\":\"https:\\\/\\\/alba.progresium.cz\\\/de\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"St\u00fchle f\u00fcr das Gesundheitswesen & Praxen | ALBA Seating","description":"St\u00fchle und Sessel f\u00fcr \u00c4rzte, Labor und medizinisches Personal sowie M\u00f6bel f\u00fcr Warte- und Empfangsbereiche. 360\u00b0-Drehung und leicht zu reinigende Oberfl\u00e4chen.","canonical_url":"https:\/\/alba.progresium.cz\/de\/loesungen\/medizin-und-pflege\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/alba.progresium.cz\/de\/loesungen\/medizin-und-pflege\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/alba.progresium.cz\/de\/#listItem","position":1,"name":"Home","item":"https:\/\/alba.progresium.cz\/de\/","nextItem":{"@type":"ListItem","@id":"https:\/\/alba.progresium.cz\/de\/loesungen\/#listItem","name":"L\u00f6sungen"}},{"@type":"ListItem","@id":"https:\/\/alba.progresium.cz\/de\/loesungen\/#listItem","position":2,"name":"L\u00f6sungen","item":"https:\/\/alba.progresium.cz\/de\/loesungen\/","nextItem":{"@type":"ListItem","@id":"https:\/\/alba.progresium.cz\/de\/loesungen\/medizin-und-pflege\/#listItem","name":"Medizin und Pflege"},"previousItem":{"@type":"ListItem","@id":"https:\/\/alba.progresium.cz\/de\/#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/alba.progresium.cz\/de\/loesungen\/medizin-und-pflege\/#listItem","position":3,"name":"Medizin und Pflege","previousItem":{"@type":"ListItem","@id":"https:\/\/alba.progresium.cz\/de\/loesungen\/#listItem","name":"L\u00f6sungen"}}]},{"@type":"Organization","@id":"https:\/\/alba.progresium.cz\/de\/#organization","name":"ALBA Seating","description":"European Chair Manufacturer","url":"https:\/\/alba.progresium.cz\/de\/"},{"@type":"WebPage","@id":"https:\/\/alba.progresium.cz\/de\/loesungen\/medizin-und-pflege\/#webpage","url":"https:\/\/alba.progresium.cz\/de\/loesungen\/medizin-und-pflege\/","name":"St\u00fchle f\u00fcr das Gesundheitswesen & Praxen | ALBA Seating","description":"St\u00fchle und Sessel f\u00fcr \u00c4rzte, Labor und medizinisches Personal sowie M\u00f6bel f\u00fcr Warte- und Empfangsbereiche. 360\u00b0-Drehung und leicht zu reinigende Oberfl\u00e4chen.","inLanguage":"de-DE","isPartOf":{"@id":"https:\/\/alba.progresium.cz\/de\/#website"},"breadcrumb":{"@id":"https:\/\/alba.progresium.cz\/de\/loesungen\/medizin-und-pflege\/#breadcrumblist"},"image":{"@type":"ImageObject","url":"https:\/\/alba.progresium.cz\/wp-content\/uploads\/2022\/02\/nemocnice1.jpg","@id":"https:\/\/alba.progresium.cz\/de\/loesungen\/medizin-und-pflege\/#mainImage","width":1920,"height":694},"primaryImageOfPage":{"@id":"https:\/\/alba.progresium.cz\/de\/loesungen\/medizin-und-pflege\/#mainImage"},"datePublished":"2022-04-08T02:35:15+02:00","dateModified":"2023-06-07T23:21:23+02:00"},{"@type":"WebSite","@id":"https:\/\/alba.progresium.cz\/de\/#website","url":"https:\/\/alba.progresium.cz\/de\/","name":"ALBA Seating","description":"European Chair Manufacturer","inLanguage":"de-DE","publisher":{"@id":"https:\/\/alba.progresium.cz\/de\/#organization"}}]},"og:locale":"de_DE","og:site_name":"ALBA Seating - European Chair Manufacturer","og:type":"article","og:title":"St\u00fchle f\u00fcr das Gesundheitswesen &amp; Praxen | ALBA Seating","og:description":"St\u00fchle und Sessel f\u00fcr \u00c4rzte, Labor und medizinisches Personal sowie M\u00f6bel f\u00fcr Warte- und Empfangsbereiche. 360\u00b0-Drehung und leicht zu reinigende Oberfl\u00e4chen.","og:url":"https:\/\/alba.progresium.cz\/de\/loesungen\/medizin-und-pflege\/","article:published_time":"2022-04-08T00:35:15+00:00","article:modified_time":"2023-06-07T21:21:23+00:00","twitter:card":"summary_large_image","twitter:title":"St\u00fchle f\u00fcr das Gesundheitswesen &amp; Praxen | ALBA Seating","twitter:description":"St\u00fchle und Sessel f\u00fcr \u00c4rzte, Labor und medizinisches Personal sowie M\u00f6bel f\u00fcr Warte- und Empfangsbereiche. 360\u00b0-Drehung und leicht zu reinigende Oberfl\u00e4chen."},"aioseo_meta_data":{"post_id":"7492","title":"St\u00fchle f\u00fcr das Gesundheitswesen & Praxen | ALBA Seating","description":"St\u00fchle und Sessel f\u00fcr \u00c4rzte, Labor und medizinisches Personal sowie M\u00f6bel f\u00fcr Warte- und Empfangsbereiche. 360\u00b0-Drehung und leicht zu reinigende Oberfl\u00e4chen.","keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2024-11-16 02:34:39","updated":"2026-06-10 23:03:54","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/alba.progresium.cz\/de\/\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/alba.progresium.cz\/de\/loesungen\/\" title=\"L\u00f6sungen\">L\u00f6sungen<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tMedizin und Pflege\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/alba.progresium.cz\/de\/"},{"label":"L\u00f6sungen","link":"https:\/\/alba.progresium.cz\/de\/loesungen\/"},{"label":"Medizin und Pflege","link":"https:\/\/alba.progresium.cz\/de\/loesungen\/medizin-und-pflege\/"}],"_links":{"self":[{"href":"https:\/\/alba.progresium.cz\/de\/wp-json\/wp\/v2\/pages\/7492","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alba.progresium.cz\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/alba.progresium.cz\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/alba.progresium.cz\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/alba.progresium.cz\/de\/wp-json\/wp\/v2\/comments?post=7492"}],"version-history":[{"count":5,"href":"https:\/\/alba.progresium.cz\/de\/wp-json\/wp\/v2\/pages\/7492\/revisions"}],"predecessor-version":[{"id":26412,"href":"https:\/\/alba.progresium.cz\/de\/wp-json\/wp\/v2\/pages\/7492\/revisions\/26412"}],"up":[{"embeddable":true,"href":"https:\/\/alba.progresium.cz\/de\/wp-json\/wp\/v2\/pages\/7480"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/alba.progresium.cz\/de\/wp-json\/wp\/v2\/media\/2292"}],"wp:attachment":[{"href":"https:\/\/alba.progresium.cz\/de\/wp-json\/wp\/v2\/media?parent=7492"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}